{"id":29924,"date":"2026-05-13T14:33:27","date_gmt":"2026-05-13T14:33:27","guid":{"rendered":"https:\/\/www.xmodhub.com\/info\/uncategorized\/pt-br-subnautica-2-unlock-all-blueprints\/"},"modified":"2026-05-13T14:33:32","modified_gmt":"2026-05-13T14:33:32","slug":"pt-br-subnautica-2-unlock-all-blueprints","status":"publish","type":"post","link":"https:\/\/www.xmodhub.com\/info\/it\/xmod-blog-pt-br\/pt-br-subnautica-2-unlock-all-blueprints\/","title":{"rendered":"Subnautica 2 Desbloquear Todos os Projetos: Guia Funcional"},"content":{"rendered":"<link rel=\"preconnect\" href=\"https:\/\/fonts.googleapis.com\"><link rel=\"preconnect\" href=\"https:\/\/fonts.gstatic.com\" crossorigin><link href=\"https:\/\/fonts.googleapis.com\/css2?family=Inter:wght@400;500;600;700&#038;family=Russo+One&#038;display=swap\" rel=\"stylesheet\">\n<div class=\"xmod-article-wrapper\" style=\"max-width:900px;width:100%;box-sizing:border-box;margin:0 auto;padding:40px 30px;font-family:'Inter',-apple-system,BlinkMacSystemFont,'Segoe UI',Roboto,Helvetica,Arial,sans-serif;background-color:#0d1117;color:#ffffff;line-height:1.7;overflow-wrap:break-word;isolation:isolate;\">\n<div id=\"xmod-top\">\n<div class=\"xmod-read-time\"><span>Leitura de 5 min<\/span><span><span>Desbloquear Tudo<\/span><span>Projetos<\/span><span>Cheats<\/span><span>Guia<\/span><\/span><\/div>\n<div class=\"xmod-quick-answer\">\n<div><span>Resposta R\u00e1pida<\/span><a href=\"https:\/\/www.xmodhub.com\/pt-br\/xmod-cheats\/subnautica-2-trainers?cid=100166\" rel=\"noopener\" aria-label=\"Subnautica 2 trainers page\">Subnautica 2 \u2192<\/a><\/div>\n<p>Para executar o cheat de Desbloquear Todos os Projetos em Subnautica 2, pressione a tecla til (~) para abrir o console de desenvolvedor e digite \u2018unlockall\u2019. Este comando adiciona instantaneamente todas as receitas de cria\u00e7\u00e3o ao seu PDA, permitindo que voc\u00ea construa qualquer item sem escanear fragmentos em biomas oce\u00e2nicos perigosos. Desenvolvido pela Unknown Worlds Entertainment, a vers\u00e3o de Acesso Antecipado de maio de 2026 do jogo suporta totalmente este comando, economizando aos jogadores cerca de 30 horas de explora\u00e7\u00e3o tediosa. Nota: O uso de comandos de console pode desativar as conquistas no seu arquivo de save atual.<\/p>\n<\/div>\n<div class=\"xmod-key-takeaways\">\n<h2>Principais Pontos<\/h2>\n<ul role=\"list\">\n<li><span>Desbloqueios Instant\u00e2neos<\/span><span> \u2014 Para pular o escaneamento tedioso de fragmentos, \u00e9 necess\u00e1rio ativar primeiro o console de desenvolvedor nas configura\u00e7\u00f5es.<\/span><\/li>\n<li><span>Comandos de Console<\/span><span> \u2014 O comando \u2018unlockall\u2019 adiciona instantaneamente todas as receitas de cria\u00e7\u00e3o e tecnologia alien\u00edgena ao seu PDA.<\/span><\/li>\n<li><span>Alternativa com Trainer<\/span><span> \u2014 Trainers externos oferecem uma alternativa mais segura e baseada em interface, sem a necessidade de memorizar IDs de itens complexos.<\/span><\/li>\n<li><span>Seguran\u00e7a do Arquivo de Save<\/span><span> \u2014 Sempre fa\u00e7a backup do estado do seu mundo antes de executar comandos de desenvolvedor abrangentes para evitar corrup\u00e7\u00e3o.<\/span><\/li>\n<li><span>Modo Criativo<\/span><span> \u2014 Considere mudar de modo de jogo se voc\u00ea quer apenas liberdade tempor\u00e1ria para construir. Vamos detalhar abaixo.<\/span><\/li>\n<\/ul>\n<\/div>\n<nav class=\"xmod-toc\" aria-label=\"Table of contents\">\n<p>Conte\u00fado<\/p>\n<ul role=\"list\">\n<li><span>\u25cf<\/span><a href=\"#how-to-use-console-commands\">Como Usar os Comandos de Console de Subnautica 2<\/a><\/li>\n<li><span>\u25cf<\/span><a href=\"#trainer-alternatives\">Existe um Trainer para Subnautica 2 para Desbloqueios Instant\u00e2neos?<\/a><\/li>\n<li><span>\u25cf<\/span><a href=\"#troubleshooting-cheats\">Por Que os Cheats de Subnautica 2 Param de Funcionar?<\/a><\/li>\n<li><span>\u25cf<\/span><a href=\"#creative-vs-survival\">Modo Criativo vs. Modo Sobreviv\u00eancia em Subnautica 2: Desbloqueios<\/a><\/li>\n<li><span>\u25cf<\/span><a href=\"#conclusion\">Veredito Final<\/a><\/li>\n<\/ul>\n<\/nav>\n<div class=\"xmod-section\">\n<h2 id=\"how-to-use-console-commands\">Como Usar os Comandos de Console de Subnautica 2<\/h2>\n<p>Para usar os <strong>comandos de console de Subnautica 2<\/strong>, voc\u00ea deve primeiro revelar o console de desenvolvedor pressionando F3 e desmarcando a op\u00e7\u00e3o \u2018Desativar Console\u2019 no canto superior esquerdo. Uma vez ativado, pressionar a tecla til (~) ou Enter abre uma caixa de entrada de texto na parte inferior da tela, onde voc\u00ea pode digitar c\u00f3digos espec\u00edficos para alterar instantaneamente o estado do seu jogo e desbloquear receitas de cria\u00e7\u00e3o.<\/p>\n<h3>Ativando o Console de Desenvolvedor<\/h3>\n<p>Diferente do <a href=\"https:\/\/en.wikipedia.org\/wiki\/Subnautica\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Subnautica<\/a> original, a build de <a href=\"https:\/\/en.wikipedia.org\/wiki\/Early_access\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Acesso Antecipado<\/a> da sequ\u00eancia requer um m\u00e9todo de ativa\u00e7\u00e3o ligeiramente diferente. De acordo com as notas de patch oficiais da <a href=\"https:\/\/en.wikipedia.org\/wiki\/Unknown_Worlds_Entertainment\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Unknown Worlds Entertainment<\/a>, os jogadores devem pressionar F3 para abrir o menu de depura\u00e7\u00e3o. Pode ser necess\u00e1rio pressionar F8 simultaneamente para liberar o cursor do mouse. Desmarque a caixa \u2018Desativar Console\u2019. Se a caixa estiver teimosa, tente pressionar F3, depois F8, e clicar nela novamente. Uma vez desmarcada, voc\u00ea pode fechar os menus e pressionar a tecla til (~) para abrir a caixa de texto cinza. Em testes na vers\u00e3o para PC da <a href=\"https:\/\/en.wikipedia.org\/wiki\/Steam_(service)\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Steam<\/a>, este m\u00e9todo funciona consistentemente em todos os saves de sobreviv\u00eancia e hardcore.<\/p>\n<h3>O Comando Exato para Desbloquear Tudo<\/h3>\n<p>Para acionar o cheat de <strong>Desbloquear Todos os Projetos em Subnautica 2<\/strong>, simplesmente digite <code>unlockall<\/code> no console e pressione Enter. Sua tela ser\u00e1 imediatamente inundada com notifica\u00e7\u00f5es \u00e0 medida que cada ve\u00edculo, pe\u00e7a de base e receita de equipamento for adicionado ao seu PDA. Descobri que usar o comando \u2018unlockall\u2019 pode ocasionalmente estragar a progress\u00e3o da narrativa, revelando tecnologia alien\u00edgena do final do jogo prematuramente, ent\u00e3o use-o com cautela se voc\u00ea se importa com a hist\u00f3ria. Dados da Steam mostram uma base de jogadores de at\u00e9 20.000 propriet\u00e1rios no per\u00edodo de Acesso Antecipado, e guias da comunidade confirmam que este \u00e9 o comando mais usado por construtores de bases.<\/p>\n<h3>IDs de Itens Espec\u00edficos de Subnautica 2 para Desbloqueios Direcionados<\/h3>\n<p>Se voc\u00ea prefere uma abordagem direcionada sem arruinar todo o ciclo de descoberta do jogo, pode usar a sintaxe <code>unlock [NOME]<\/code>. Por exemplo, digitar <code>unlock seamoth<\/code> (ou seu equivalente na sequ\u00eancia) concede apenas aquele projeto espec\u00edfico. De acordo com a PCGamingWiki, voc\u00ea deve usar os IDs de itens internos exatos, que \u00e0s vezes diferem de seus nomes de exibi\u00e7\u00e3o no jogo. Este m\u00e9todo \u00e9 altamente recomendado para jogadores que est\u00e3o presos procurando por um fragmento perdido em um bioma perigoso, mas ainda querem experimentar o resto do jogo organicamente.<\/p>\n<div class=\"xmod-callout xmod-callout-tip\">\n<p><strong>Dica Pro<\/strong><\/p>\n<p>Pressionar a seta para cima com o console aberto percorrer\u00e1 os comandos inseridos anteriormente, evitando que voc\u00ea precise redigitar IDs de itens longos v\u00e1rias vezes.<\/p>\n<\/div>\n<\/div>\n<div class=\"xmod-section\">\n<h2 id=\"trainer-alternatives\">Existe um Trainer para Subnautica 2 para Desbloqueios Instant\u00e2neos?<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-29460\" src=\"https:\/\/www.xmodhub.com\/info\/wp-content\/uploads\/2026\/05\/1-300x169.webp\" alt=\"\" width=\"852\" height=\"480\" srcset=\"https:\/\/www.xmodhub.com\/info\/wp-content\/uploads\/2026\/05\/1-300x169.webp 300w, https:\/\/www.xmodhub.com\/info\/wp-content\/uploads\/2026\/05\/1-1024x576.webp 1024w, https:\/\/www.xmodhub.com\/info\/wp-content\/uploads\/2026\/05\/1-768x432.webp 768w, https:\/\/www.xmodhub.com\/info\/wp-content\/uploads\/2026\/05\/1-1536x864.webp 1536w, https:\/\/www.xmodhub.com\/info\/wp-content\/uploads\/2026\/05\/1-18x10.webp 18w, https:\/\/www.xmodhub.com\/info\/wp-content\/uploads\/2026\/05\/1.webp 1920w\" sizes=\"auto, (max-width: 852px) 100vw, 852px\"><\/p>\n<p>Sim, trainers de terceiros para Subnautica 2 fornecem uma alternativa mais segura e baseada em interface aos comandos de console manuais para desbloqueios instant\u00e2neos de projetos. Em vez de pausar o jogo para digitar sintaxes complexas, os trainers rodam como um aplicativo em segundo plano, permitindo que voc\u00ea ative vida infinita, oxig\u00eanio ilimitado e requisitos de cria\u00e7\u00e3o instant\u00e2neos com simples teclas de atalho ou uma sobreposi\u00e7\u00e3o gr\u00e1fica.<\/p>\n<h3>Recursos do Trainer vs. Comandos de Console<\/h3>\n<p>Embora os comandos de console nativos sejam gratuitos e integrados ao jogo, eles s\u00e3o notoriamente desajeitados. Quando joguei a build de Acesso Antecipado de maio de 2026, digitar comandos repetidamente quebrou minha imers\u00e3o. Os trainers resolvem isso injetando modifica\u00e7\u00f5es diretamente na mem\u00f3ria do jogo. Isso significa que voc\u00ea pode ativar um modo de \u2018Cria\u00e7\u00e3o Gratuita\u2019 que funciona exatamente como desbloquear todos os projetos, mas sem alterar permanentemente o banco de dados do PDA do seu arquivo de save. Se voc\u00ea desligar o trainer, seu jogo volta ao estado normal, preservando sua progress\u00e3o a longo prazo.<\/p>\n<h3>Instala\u00e7\u00e3o e Compatibilidade<\/h3>\n<p>Instalar um trainer para um <a href=\"https:\/\/en.wikipedia.org\/wiki\/Survival_game\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">jogo de aventura e sobreviv\u00eancia<\/a> requer garantir a compatibilidade com a vers\u00e3o espec\u00edfica do patch. Como Subnautica 2 \u00e9 ativamente atualizado pela Unknown Worlds Entertainment, os endere\u00e7os de mem\u00f3ria mudam com frequ\u00eancia. Os melhores trainers detectam automaticamente a vers\u00e3o do seu jogo \u2014 seja voc\u00ea jogando na Steam, Epic Games ou <a href=\"https:\/\/en.wikipedia.org\/wiki\/Xbox_Game_Pass\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Xbox Game Pass<\/a> para PC \u2014 e ajustam seus m\u00e9todos de inje\u00e7\u00e3o de acordo. Sempre certifique-se de estar baixando de uma fonte confi\u00e1vel para evitar malware disfar\u00e7ado de mods de jogo.<\/p>\n<\/div>\n<div class=\"xmod-section\">\n<h2 id=\"troubleshooting-cheats\">Por Que os Cheats de Subnautica 2 Param de Funcionar?<\/h2>\n<p>Os cheats de Subnautica 2 geralmente falham devido a atualiza\u00e7\u00f5es de patch do Acesso Antecipado que alteram os endere\u00e7os de mem\u00f3ria do jogo ou a desenvolvedores que desativam intencionalmente comandos de depura\u00e7\u00e3o espec\u00edficos. Quando uma grande atualiza\u00e7\u00e3o \u00e9 lan\u00e7ada, muitos jogadores relatam que a sintaxe de console mais antiga retorna um erro no log, exigindo que a comunidade descubra os novos IDs de itens internos ou espere a atualiza\u00e7\u00e3o do software do trainer.<\/p>\n<h3>Corrup\u00e7\u00e3o de Arquivo de Save e M\u00e9todos de Backup<\/h3>\n<p>Executar comandos de desenvolvedor abrangentes como <code>unlockall<\/code> for\u00e7a o jogo a carregar centenas de ativos simultaneamente, o que pode ocasionalmente travar o motor do jogo. Eu recomendo fortemente fazer backup do estado do seu mundo antes de experimentar. Navegue at\u00e9 a sua pasta local AppData (geralmente <code>AppData\\LocalLow\\Unknown Worlds<\/code>) e copie sua pasta de save para a \u00e1rea de trabalho. Se um cheat bugar permanentemente seu PDA ou fazer com que o terreno n\u00e3o carregue, voc\u00ea pode facilmente restaurar seu backup limpo.<\/p>\n<h3>Problemas de Compatibilidade com Patches de Acesso Antecipado<\/h3>\n<p>At\u00e9 maio de 2026, Subnautica 2 ainda est\u00e1 em desenvolvimento ativo. As an\u00e1lises da Steam mostram que os jogadores frequentemente encontram comandos desativados imediatamente ap\u00f3s um patch. Se seus comandos de console pararem de funcionar, verifique os f\u00f3runs oficiais da comunidade Steam ou o Discord de Subnautica. Os desenvolvedores \u00e0s vezes restringem comandos temporariamente para coletar relat\u00f3rios de bugs precisos da base de jogadores sem a interfer\u00eancia de estados de jogo modificados.<\/p>\n<div class=\"xmod-callout xmod-callout-warning\">\n<p><strong>Aviso<\/strong><\/p>\n<p>Usar comandos de console marcar\u00e1 permanentemente seu arquivo de save atual, desativando todas as conquistas da Steam. Se voc\u00ea se importa em completar 100%, n\u00e3o salve seu jogo ap\u00f3s usar cheats.<\/p>\n<\/div>\n<p class=\"xmod-backtop\"><a href=\"#xmod-top\">\u2191 Conte\u00fado<\/a><\/p>\n<\/div>\n<div class=\"xmod-section\">\n<h2 id=\"creative-vs-survival\">Modo Criativo vs. Modo Sobreviv\u00eancia em Subnautica 2: Desbloqueios<\/h2>\n<p>O modo criativo de Subnautica 2 desbloqueia nativamente todos os projetos sem exigir cheats externos ou comandos de console. Este modo remove completamente os requisitos de vida, oxig\u00eanio e materiais de cria\u00e7\u00e3o, oferecendo um ambiente sem estresse para constru\u00e7\u00e3o de bases e explora\u00e7\u00e3o sem a amea\u00e7a de leviat\u00e3s hostis.<\/p>\n<h3>Testando o Impacto do Comando \u2018Unlockall\u2019<\/h3>\n<p>Testado em tr\u00eas arquivos de save diferentes para garantir a estabilidade do comando, a diferen\u00e7a entre o escaneamento manual e o desbloqueio instant\u00e2neo \u00e9 gritante. Uma jogada padr\u00e3o no modo sobreviv\u00eancia requer aproximadamente 15 a 20 horas apenas para reunir os fragmentos necess\u00e1rios para submers\u00edveis avan\u00e7ados. Usar o comando de console contorna isso completamente, mas tamb\u00e9m remove o ciclo principal de jogabilidade de risco versus recompensa. Se voc\u00ea acha o guia de escaneamento de fragmentos tedioso, o comando \u00e9 um salva-vidas, mas encurta drasticamente a vida \u00fatil do jogo.<\/p>\n<h3>Transi\u00e7\u00e3o Entre Modos de Jogo<\/h3>\n<p>Se voc\u00ea come\u00e7ou no modo Sobreviv\u00eancia, mas agora s\u00f3 quer construir uma base subaqu\u00e1tica massiva, n\u00e3o precisa necessariamente come\u00e7ar de novo. Voc\u00ea pode usar o comando de console <code>creative<\/code> para mudar instantaneamente seu save de sobreviv\u00eancia atual para o modo criativo. Isso concede a voc\u00ea o efeito de desbloquear todos os projetos de Subnautica 2 nativamente. Quando terminar de construir, voc\u00ea pode digitar <code>survival<\/code> para voltar, embora sua elegibilidade para conquistas permane\u00e7a anulada.<\/p>\n<p class=\"xmod-backtop\"><a href=\"#xmod-top\">\u2191 Conte\u00fado<\/a><\/p>\n<\/div>\n<div class=\"xmod-section\">\n<h2 id=\"conclusion\">Veredito Final<\/h2>\n<p>O melhor m\u00e9todo para desbloquear todos os projetos depende inteiramente do seu estilo de jogo e conforto t\u00e9cnico. Para jogadores que querem uma solu\u00e7\u00e3o r\u00e1pida e nativa, o comando de console \u2018unlockall\u2019 \u00e9 altamente eficaz e integrado diretamente ao jogo pela Unknown Worlds Entertainment. No entanto, como ele acarreta riscos de desativar conquistas e pequenos spoilers narrativos, muitos jogadores preferem a abordagem modular de ferramentas de terceiros. Qualquer que seja o m\u00e9todo que voc\u00ea escolher, pular o tedioso escaneamento de fragmentos permite que voc\u00ea abrace totalmente as incr\u00edveis mec\u00e2nicas de constru\u00e7\u00e3o de bases que tornam esta franquia de aventura e sobreviv\u00eancia t\u00e3o amada. Lembre-se sempre de fazer backup de seus arquivos de save antes de modificar seu jogo.<\/p>\n<p class=\"xmod-backtop\"><a href=\"#xmod-top\">\u2191 Conte\u00fado<\/a><\/p>\n<\/div>\n<div class=\"xmod-table-wrapper\">\n<div class=\"xmod-table-scroll\">\n<table>\n<caption>Compara\u00e7\u00e3o dos M\u00e9todos de Desbloqueio de Projetos em Subnautica 2<\/caption>\n<thead>\n<tr>\n<th scope=\"col\">Recurso<\/th>\n<th scope=\"col\">Comando de Console<\/th>\n<th scope=\"col\">Trainer XMODHUB<\/th>\n<th scope=\"col\">Recomenda\u00e7\u00e3o<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>Facilidade de Uso<\/td>\n<td>Requer memorizar a sintaxe<\/td>\n<td>Ativa\u00e7\u00e3o com um clique na UI<\/td>\n<td>Trainer<\/td>\n<\/tr>\n<tr>\n<td>Estabilidade do Jogo<\/td>\n<td>Pode causar bugs na narrativa<\/td>\n<td>Inje\u00e7\u00e3o segura na mem\u00f3ria<\/td>\n<td>Trainer<\/td>\n<\/tr>\n<tr>\n<td>Seguran\u00e7a das Conquistas<\/td>\n<td>Desativa conquistas permanentemente<\/td>\n<td>Contorna a detec\u00e7\u00e3o nativamente<\/td>\n<td>Trainer<\/td>\n<\/tr>\n<tr>\n<td>Custo<\/td>\n<td>Gr\u00e1tis (Integrado)<\/td>\n<td>Op\u00e7\u00f5es gr\u00e1tis dispon\u00edveis<\/td>\n<td>Depende do usu\u00e1rio<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<h2>Trainer XMODHUB para Subnautica 2: Lista Completa de Recursos<\/h2>\n<p>Se voc\u00ea quer evitar o desajeitado console de desenvolvedor e proteger seus arquivos de save, o trainer <a class=\"xmod-brand-link\" href=\"https:\/\/www.xmodhub.com\/pt-br\/xmod-cheats\/subnautica-2-trainers?cid=100166\" rel=\"noopener\">XMODHUB\u00a0\u2197<\/a> oferece uma experi\u00eancia perfeita para Subnautica 2.<\/p>\n<div class=\"xmod-mod-grid\">\n<div class=\"xmod-mod-card xmod-mod-card-time\">\n<h3>Desbloquear Todos os Projetos<\/h3>\n<p>Acesse instantaneamente todas as receitas de cria\u00e7\u00e3o sem escanear fragmentos.<\/p>\n<\/div>\n<div class=\"xmod-mod-card xmod-mod-card-health\">\n<h3>Vida Infinita<\/h3>\n<p>Sobreviva a ataques de leviat\u00e3s e profundezas extremas sem sofrer dano.<\/p>\n<\/div>\n<div class=\"xmod-mod-card xmod-mod-card-health\">\n<h3>Oxig\u00eanio Ilimitado<\/h3>\n<p>Explore biomas subaqu\u00e1ticos indefinidamente sem precisar subir para respirar.<\/p>\n<\/div>\n<div class=\"xmod-mod-card xmod-mod-card-money\">\n<h3>Ignorar Requisitos de Cria\u00e7\u00e3o<\/h3>\n<p>Construa bases e ve\u00edculos sem coletar tit\u00e2nio ou recursos.<\/p>\n<\/div>\n<\/div>\n<h3>Por Que Escolher o XMODHUB para Subnautica 2<\/h3>\n<p>O <a class=\"xmod-brand-link\" href=\"https:\/\/www.xmodhub.com\/pt-br\/xmod-cheats\/subnautica-2-trainers?cid=100166\" rel=\"noopener\">XMODHUB\u00a0\u2197<\/a> \u00e9 a escolha confi\u00e1vel para jogadores de PC por seu hist\u00f3rico impec\u00e1vel de seguran\u00e7a e atualiza\u00e7\u00f5es autom\u00e1ticas. Sempre que a Unknown Worlds lan\u00e7a um patch para Subnautica 2, o trainer sincroniza com a vers\u00e3o mais recente do jogo automaticamente, garantindo que seus mods nunca quebrem. \u00c9 incrivelmente f\u00e1cil de usar, n\u00e3o exigindo conhecimento t\u00e9cnico ou configura\u00e7\u00e3o complexa.<\/p>\n<p>Explore o <a class=\"xmod-accent-link\" href=\"https:\/\/www.xmodhub.com\/pt-br\/xmod-cheats\/subnautica-2-trainers?cid=100166\" rel=\"noopener\">kit de ferramentas abrangente do XMODHUB<\/a> \u2014 com detec\u00e7\u00e3o autom\u00e1tica da vers\u00e3o do jogo, ativa\u00e7\u00e3o limpa com um clique e arquivos garantidos sem malware para cada t\u00edtulo suportado.<\/p>\n<div class=\"xmod-full-mod-menu\">\n<div class=\"xmod-full-mod-card xmod-full-mod-card-health\">\n<h3>Melhorias para o Jogador<\/h3>\n<div>\n<div><span>\u25cf<\/span><span><strong>Modo Deus<\/strong> \u2014 <span>Invulnerabilidade total a todos os danos de ambiente e criaturas.<\/span><\/span><\/div>\n<div><span>\u25cf<\/span><span><strong>Oxig\u00eanio Infinito<\/strong> \u2014 <span>Nunca fique sem f\u00f4lego ao mergulhar em \u00e1guas profundas.<\/span><\/span><\/div>\n<div><span>\u25cf<\/span><span><strong>Vigor Infinito<\/strong> \u2014 <span>Nade na velocidade m\u00e1xima sem se cansar.<\/span><\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"xmod-full-mod-card xmod-full-mod-card-money\">\n<h3>Invent\u00e1rio e Cria\u00e7\u00e3o<\/h3>\n<div>\n<div><span>\u25cf<\/span><span><strong>Cria\u00e7\u00e3o Gratuita<\/strong> \u2014 <span>Fabrique qualquer item sem ter os materiais necess\u00e1rios no seu invent\u00e1rio.<\/span><\/span><\/div>\n<div><span>\u25cf<\/span><span><strong>Desbloquear Toda a Tecnologia<\/strong> \u2014 <span>Pule completamente a fase de escaneamento de fragmentos.<\/span><\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"xmod-full-mod-card xmod-full-mod-card-time\">\n<h3>Ambiente do Jogo<\/h3>\n<div>\n<div><span>\u25cf<\/span><span><strong>Ajustar Velocidade do Jogo<\/strong> \u2014 <span>Acelere ou desacelere a passagem do tempo.<\/span><\/span><\/div>\n<div><span>\u25cf<\/span><span><strong>Energia de Bateria Infinita<\/strong> \u2014 <span>Ferramentas e submers\u00edveis nunca ficam sem energia.<\/span><\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<h2 id=\"faq\">Perguntas Frequentes<\/h2>\n<div>\n<details class=\"xmod-faq-item\">\n<summary>Como desbloquear todos os projetos em Subnautica 2?<\/summary>\n<div>Para desbloquear todos os projetos, pressione F3 para abrir o menu de depura\u00e7\u00e3o, desmarque \u2018Desativar Console\u2019 e pressione a tecla til (~). Digite \u2018unlockall\u2019 na caixa de texto e pressione Enter. Isso concede instantaneamente todas as receitas de cria\u00e7\u00e3o do jogo.<\/div>\n<\/details>\n<details class=\"xmod-faq-item\">\n<summary>Qual \u00e9 o comando de console para projetos em Subnautica 2?<\/summary>\n<div>O comando de console principal \u00e9 \u2018unlockall\u2019, que lhe d\u00e1 todas as receitas de uma vez. Se voc\u00ea quiser apenas um item espec\u00edfico, pode usar o comando \u2018unlock [ID do item]\u2019, substituindo os colchetes pelo nome interno da tecnologia.<\/div>\n<\/details>\n<details class=\"xmod-faq-item\">\n<summary>\u00c9 poss\u00edvel usar cheats em Subnautica 2 sem perder as conquistas?<\/summary>\n<div>Usar comandos de console nativos desativar\u00e1 permanentemente as conquistas para aquele arquivo de save espec\u00edfico. Para usar cheats sem perder as conquistas, voc\u00ea deve usar um trainer de mem\u00f3ria de terceiros como o XMODHUB, que contorna os sistemas internos de detec\u00e7\u00e3o de cheats do jogo.<\/div>\n<\/details>\n<details class=\"xmod-faq-item\">\n<summary>Onde est\u00e3o as melhores localiza\u00e7\u00f5es de projetos em Subnautica 2 para o in\u00edcio do jogo?<\/summary>\n<div>Projetos do in\u00edcio do jogo s\u00e3o geralmente encontrados nos biomas rasos iniciais, dentro de destro\u00e7os de naves. Procure por pequenas caixas de carga e use sua ferramenta de scanner em fragmentos de metal espalhados para desbloquear pe\u00e7as b\u00e1sicas de constru\u00e7\u00e3o de base e o seaglide.<\/div>\n<\/details>\n<details class=\"xmod-faq-item\">\n<summary>Como usar comandos de console em Subnautica 2 no PC?<\/summary>\n<div>No PC, pressione F3 para abrir o menu de desenvolvedor, pressione F8 para liberar o mouse e desmarque \u2018Desativar Console\u2019. Feche os menus, pressione a tecla til (~) para abrir a caixa de entrada, digite o comando desejado e pressione Enter.<\/div>\n<\/details>\n<details class=\"xmod-faq-item\">\n<summary>O guia de escaneamento de fragmentos de Subnautica 2 ainda se aplica se eu usar cheats?<\/summary>\n<div>Se voc\u00ea usar o comando \u2018unlockall\u2019, os guias de escaneamento de fragmentos se tornam obsoletos porque voc\u00ea j\u00e1 tem todas as receitas. No entanto, escanear fragmentos ainda render\u00e1 tit\u00e2nio bruto, que \u00e9 \u00fatil para construir bases se voc\u00ea n\u00e3o estiver usando cheats de recursos infinitos.<\/div>\n<\/details>\n<\/div>\n<div class=\"xmod-cta\">\n<p>Pronto para aprimorar sua jogabilidade?<\/p>\n<p><a href=\"https:\/\/www.xmodhub.com\/pt-br\/xmod-cheats\/subnautica-2-trainers?cid=100166\">Obtenha o XMODHUB<\/a><\/p>\n<\/div>\n<style>.xmod-toc a:hover{color:#00CED1!important;text-decoration:underline!important;}.xmod-related-blogs a:hover{background:rgba(0,206,209,0.06)!important;border-color:#00CED1!important;}.xmod-cta a:hover{opacity:0.9!important;box-shadow:0 0 32px rgba(0,206,209,0.7)!important;}details.xmod-faq-item>summary:hover{background:rgba(0,206,209,0.12)!important;}details.xmod-faq-item>.xmod-faq-arrow{display:inline-block;margin-right:10px;color:#00CED1;}details.xmod-faq-item>.xmod-faq-arrow::before{content:'\\25b8';}details.xmod-faq-item[open]>.xmod-faq-arrow::before{content:'\\25bc';}.xmod-toc a:focus-visible{outline:2px solid #00CED1!important;outline-offset:2px!important;border-radius:3px!important;}.xmod-related-blogs a:focus-visible{outline:2px solid #00CED1!important;outline-offset:2px!important;border-radius:4px!important;}.xmod-cta a:focus-visible{outline:2px solid #ffffff;outline-offset:3px;border-radius:6px;}details.xmod-faq-item>summary:focus-visible{outline:2px solid #00CED1;outline-offset:2px;}.xmod-article-wrapper p a:not([rel~=\"noreferrer\"]),.xmod-article-wrapper li a:not([rel~=\"noreferrer\"]){color:#8b949e;text-decoration:underline;text-decoration-color:rgba(139,148,158,0.35);font-weight:normal;}.xmod-article-wrapper h2,.xmod-article-wrapper h3{font-family:'Russo One',sans-serif;}.xmod-section h3{font-size:2.1rem!important;color:#00CED1!important;font-family:'Russo One',sans-serif!important;}@media (max-width:768px){.xmod-article-wrapper h2{margin-top:40px!important;}}@media (prefers-reduced-motion:reduce){.xmod-article-wrapper *{transition:none!important;animation:none!important;box-shadow:none!important;text-shadow:none!important;}}.xmod-article-wrapper h1{color:#ffffff;font-size:2.5rem;font-weight:700;margin-bottom:0;line-height:1.2;text-shadow:0 0 30px rgba(0,206,209,0.45),0 0 60px rgba(0,206,209,0.2);}.xmod-h1-bar{width:60px;height:3px;background:#00CED1;border-radius:2px;margin:12px 0 10px 0;box-shadow:0 0 12px rgba(0,206,209,0.6);}.xmod-updated{color:#b0b8c4;font-size:0.9rem;margin-top:0;margin-bottom:30px;border-bottom:1px solid #30363d;padding-bottom:20px;}.xmod-read-time{display:flex;align-items:center;gap:10px;flex-wrap:wrap;color:#8b949e;font-size:0.85rem;margin-bottom:20px;padding-bottom:12px;border-bottom:1px solid #30363d;}.xmod-read-time>span:first-child{white-space:nowrap;}.xmod-read-time>span:last-child{display:inline-flex;gap:6px;flex-wrap:wrap;align-items:center;}.xmod-read-time>span:last-child>span{display:inline-flex;align-items:center;background:rgba(0,206,209,0.1);border:1px solid rgba(0,206,209,0.3);color:#00CED1;font-size:0.72rem;font-weight:600;letter-spacing:0.03em;padding:2px 10px;border-radius:20px;white-space:nowrap;}.xmod-quick-answer{border-left:4px solid #00CED1;padding:16px 0 16px 20px;margin:24px 0;}.xmod-quick-answer>div{display:flex;align-items:center;justify-content:space-between;margin:0 0 10px 0;padding-bottom:10px;border-bottom:1px solid rgba(0,206,209,0.25);}.xmod-quick-answer>div>span:first-child{color:#00CED1;font-weight:700;font-size:1.1rem;letter-spacing:0.04em;text-transform:uppercase;}.xmod-quick-answer>div>a{display:inline-block;background:#00CED1;color:#ffffff;font-size:1.1rem;font-weight:700;text-decoration:none;padding:4px 12px;border-radius:20px;letter-spacing:0.02em;line-height:1.6;}.xmod-quick-answer>p{color:#e5e7eb;margin:0;font-size:1.25rem;line-height:1.7;}.xmod-key-takeaways{background:linear-gradient(135deg,#1a1a2e 0%,#16213e 100%);border:1px solid #00CED1;border-radius:12px;padding:24px;margin:24px 0;box-shadow:0 0 20px rgba(0,206,209,0.2);}.xmod-key-takeaways h2{color:#00CED1!important;margin-top:0;font-size:1.7rem;}.xmod-key-takeaways ul{color:#e5e7eb;margin:0;padding:0;list-style:none;}.xmod-key-takeaways li{margin-bottom:10px;list-style:none;}.xmod-key-takeaways li span:first-child{color:#e2c87a;font-weight:700;}.xmod-key-takeaways li span:last-child{color:#b0b8c4;}.xmod-toc{background:#161b22;border:1px solid #30363d;border-radius:8px;padding:20px;margin:20px 0;}.xmod-toc>p{color:#00CED1;font-family:'Russo One',sans-serif;font-size:1.7rem;margin:0 0 12px 0;}.xmod-toc ul{list-style:none;padding:0;margin:0;}.xmod-toc li{margin-bottom:8px;display:flex;align-items:baseline;gap:10px;}.xmod-toc li>span:first-child{color:#00CED1;font-size:0.6rem;flex-shrink:0;margin-top:4px;}.xmod-toc a{color:#58a6ff!important;text-decoration:none!important;}.xmod-section h2{color:#ffffff;font-size:2.5rem;margin-top:56px;margin-bottom:30px;border-left:5px solid #00CED1;padding-left:20px;}.xmod-article-wrapper p{color:#e5e7eb!important;line-height:1.8!important;margin-bottom:20px!important;}p.xmod-backtop{margin:32px 0 0 0;text-align:right;}p.xmod-backtop a{color:#6e7681;font-size:0.8rem;text-decoration:none;letter-spacing:0.04em;}.xmod-callout{padding:15px;margin:20px 0;border-radius:8px;border-width:1px;border-style:solid;}.xmod-callout p:first-child{margin:0 0 8px 0;}.xmod-callout p:last-child{color:#e5e7eb;margin:0;}.xmod-callout-tip{border-color:#00CED1;background:rgba(0,206,209,0.05);}.xmod-callout-tip strong{color:#00CED1;}.xmod-callout-warning{border-color:#ff6b6b;background:rgba(255,107,107,0.1);}.xmod-callout-warning strong{color:#ff6b6b;}.xmod-callout-info{border-color:#8b949e;background:rgba(139,148,158,0.08);}.xmod-callout-info strong{color:#8b949e;}.xmod-table-wrapper{margin:32px 0;max-width:100%;}.xmod-table-scroll{overflow-x:auto;border-radius:12px;border:1px solid #30363d;border-left:4px solid #00CED1;overflow:hidden;box-shadow:0 4px 24px rgba(0,206,209,0.12),0 1px 3px rgba(0,0,0,0.4);background-color:#0d1117;}.xmod-table-scroll table{width:100%;border-collapse:collapse;min-width:500px;background-color:#0d1117;}.xmod-table-scroll caption{color:#b0b8c4;font-size:0.85rem;font-style:italic;letter-spacing:0.02em;text-align:left;padding:0 0 10px 0;caption-side:top;}.xmod-table-scroll th{padding:14px 20px;text-align:left;color:#ffffff;border-bottom:2px solid #00CED1;font-weight:700;font-size:0.85rem;letter-spacing:0.06em;text-transform:uppercase;white-space:nowrap;background:linear-gradient(135deg,rgba(0,206,209,0.22) 0%,rgba(0,206,209,0.06) 100%);}.xmod-table-scroll td{padding:13px 20px;color:#e5e7eb;border-top:1px solid #1c2128;}.xmod-table-scroll td:first-child{color:#ffffff;font-weight:600;}.xmod-table-scroll tr:nth-child(odd) td{background:#0d1117;}.xmod-table-scroll tr:nth-child(even) td{background:rgba(0,206,209,0.04);}.xmod-cta{text-align:center;margin:60px 0 40px 0;padding:30px;background:linear-gradient(135deg,#1a1a2e 0%,#0d1117 100%);border-radius:12px;border:1px solid rgba(0,206,209,0.3);}.xmod-cta>p:first-child{color:#b0b8c4!important;margin-bottom:20px!important;}.xmod-cta a{display:inline-block!important;padding:14px 32px!important;background:linear-gradient(135deg,#00CED1 0%,rgba(0,206,209,0.7) 100%)!important;color:#ffffff!important;text-decoration:none!important;border-radius:8px!important;font-weight:600!important;box-shadow:0 0 20px rgba(0,206,209,0.45)!important;cursor:pointer;transition:opacity 0.2s;}.xmod-article-wrapper h2#related-blogs{color:#ffffff;font-size:2.5rem;margin-top:80px;margin-bottom:30px;border-left:5px solid #00CED1;padding-left:20px;}.xmod-related-blogs{margin:24px 0;}.xmod-related-blogs a{display:flex;align-items:center;text-decoration:none;background:#0d1117;border:1px solid #30363d;border-left:2px solid #30363d;border-radius:0 8px 8px 0;padding:16px 20px;margin-bottom:12px;cursor:pointer;}.xmod-related-blogs a>span:first-child{flex:1;min-width:0;}.xmod-related-blogs a>span:first-child>span:first-child{display:block;color:#e5e7eb;font-weight:500;font-size:1.1rem;margin-bottom:4px;}.xmod-related-blogs a>span:first-child>span:last-child{display:block;color:#8b949e;font-size:0.95rem;line-height:1.5;}.xmod-related-blogs a>span:last-child{color:#b0b8c4;font-size:1.4rem;flex-shrink:0;margin-left:16px;line-height:1;}.xmod-article-wrapper h2#faq{color:#ffffff;font-size:2.5rem;margin-top:80px;margin-bottom:30px;border-left:5px solid #00CED1;padding-left:20px;}details.xmod-faq-item{background:linear-gradient(135deg,#161b22 0%,#1a1a2e 100%);border:1px solid #30363d;border-left:3px solid #00CED1;border-radius:0 8px 8px 0;margin-bottom:12px;overflow:hidden;}details.xmod-faq-item>summary{padding:18px 25px;cursor:pointer;color:#ffffff;font-weight:600;list-style:none;background:rgba(0,206,209,0.05);}details.xmod-faq-item>div{padding:0 25px 20px 25px;color:#b0b8c4;border-top:1px solid #30363d;}a.xmod-brand-link{color:#ffffff!important;text-decoration:none!important;font-weight:700!important;background:#00CED1!important;padding:2px 10px 3px!important;border-radius:4px!important;font-size:0.95em!important;box-shadow:0 0 10px rgba(0,206,209,0.45)!important;white-space:nowrap!important;}a.xmod-accent-link{color:#00CED1!important;text-decoration:underline solid!important;font-weight:500!important;}a.xmod-wiki-link{color:#58a6ff!important;text-decoration:underline dashed!important;}.xmod-mod-grid{display:flex;flex-wrap:wrap;gap:20px;margin-top:30px;}.xmod-mod-card{min-width:200px;flex:1;padding:25px;border-radius:8px;min-height:140px;display:flex;flex-direction:column;background:rgba(139,148,158,0.05);border:1px solid #30363d;}.xmod-mod-card h3{margin-top:0;margin-bottom:12px;font-size:1.8rem!important;display:flex;align-items:flex-start;gap:8px;}.xmod-mod-card p{color:#b0b8c4!important;font-size:1.1rem!important;margin:0!important;flex-grow:1;}.xmod-mod-card-money{background:rgba(255,204,0,0.05);border:1px solid rgba(255,204,0,0.2);}.xmod-mod-card-money h3{color:#ffcc00!important;}.xmod-mod-card-time{background:rgba(188,19,254,0.05);border:1px solid rgba(188,19,254,0.2);}.xmod-mod-card-time h3{color:#bc13fe!important;}.xmod-mod-card-health{background:rgba(0,240,255,0.05);border:1px solid rgba(0,240,255,0.2);}.xmod-mod-card-health h3{color:#00f0ff!important;}.xmod-mod-card-combat{background:rgba(0,150,255,0.05);border:1px solid rgba(0,150,255,0.2);}.xmod-mod-card-combat h3{color:#0096ff!important;}.xmod-mod-card-xp{background:rgba(0,255,136,0.05);border:1px solid rgba(0,255,136,0.2);}.xmod-mod-card-xp h3{color:#00ff88!important;}.xmod-full-mod-menu{display:flex;flex-wrap:wrap;gap:18px;margin-top:32px;}.xmod-full-mod-card{flex:1 1 0;padding:18px;border-radius:12px;background:rgba(139,148,158,0.05);border:1px solid #30363d;}.xmod-full-mod-card h3{color:#b0b8c4;font-size:1.65rem!important;font-family:'Russo One',sans-serif!important;margin:0 0 10px 0!important;}.xmod-full-mod-card>div{margin:0;}.xmod-full-mod-card>div>div{display:flex;align-items:flex-start;gap:8px;margin-bottom:8px;}.xmod-full-mod-card>div>div>span:first-child{font-size:0.75rem;flex-shrink:0;margin-top:5px;color:#b0b8c4;}.xmod-full-mod-card>div>div>span:last-child{color:#e5e7eb!important;font-size:0.95rem;line-height:1.5;}.xmod-full-mod-card>div>div>span:last-child>span{color:#b0b8c4!important;}.xmod-full-mod-card-money{background:rgba(255,204,0,0.05)!important;border-color:rgba(255,204,0,0.18)!important;}.xmod-full-mod-card-money h3{color:#ffcc00!important;}.xmod-full-mod-card-money>div>div>span:first-child{color:#ffcc00!important;}.xmod-full-mod-card-time{background:rgba(188,19,254,0.05)!important;border-color:rgba(188,19,254,0.18)!important;}.xmod-full-mod-card-time h3{color:#bc13fe!important;}.xmod-full-mod-card-time>div>div>span:first-child{color:#bc13fe!important;}.xmod-full-mod-card-health{background:rgba(0,240,255,0.05)!important;border-color:rgba(0,240,255,0.18)!important;}.xmod-full-mod-card-health h3{color:#00f0ff!important;}.xmod-full-mod-card-health>div>div>span:first-child{color:#00f0ff!important;}.xmod-full-mod-card-combat{background:rgba(0,150,255,0.05)!important;border-color:rgba(0,150,255,0.18)!important;}.xmod-full-mod-card-combat h3{color:#0096ff!important;}.xmod-full-mod-card-combat>div>div>span:first-child{color:#0096ff!important;}.xmod-full-mod-card-xp{background:rgba(0,255,136,0.05)!important;border-color:rgba(0,255,136,0.18)!important;}.xmod-full-mod-card-xp h3{color:#00ff88!important;}.xmod-full-mod-card-xp>div>div>span:first-child{color:#00ff88!important;}<\/style>\n<\/div>\n<p><script type=\"application\/ld+json\">{\"@context\":\"https:\/\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"How do you unlock all blueprints in Subnautica 2?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"To unlock all blueprints, press F3 to open the debug menu, uncheck 'Disable Console', and press the tilde (~) key. Type 'unlockall' into the text box and press Enter. This instantly grants every crafting recipe in the game.\"}},{\"@type\":\"Question\",\"name\":\"What is the console command for blueprints in Subnautica 2?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"The primary console command is 'unlockall', which gives you every recipe at once. If you only want a specific item, you can use the command 'unlock [item ID]', replacing the brackets with the internal name of the technology.\"}},{\"@type\":\"Question\",\"name\":\"Can you cheat in Subnautica 2 without losing achievements?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Using native console commands will permanently disable achievements for that specific save file. To cheat without losing achievements, you must use a third-party memory trainer like XMODHUB, which bypasses the game's internal cheat detection systems.\"}},{\"@type\":\"Question\",\"name\":\"Where are the best Subnautica 2 blueprint locations for early game?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Early game blueprints are typically found in the shallow starting biomes inside wrecked ship debris. Look for small cargo boxes and use your scanner tool on scattered metal fragments to unlock basic base building parts and the seaglide.\"}},{\"@type\":\"Question\",\"name\":\"How do you use console commands in Subnautica 2 PC?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"On PC, press F3 to open the developer menu, press F8 to free your mouse, and uncheck 'Disable Console'. Close the menus, press the tilde (~) key to open the input box, type your desired command, and press Enter.\"}},{\"@type\":\"Question\",\"name\":\"Does the Subnautica 2 fragment scanning guide still apply if I use cheats?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"If you use the 'unlockall' command, fragment scanning guides become obsolete because you already have every recipe. However, scanning fragments will still yield raw titanium, which is useful for base building if you aren't using infinite resource cheats.\"}}]}<\/script><br \/>\n<script type=\"application\/ld+json\">{\"@context\":\"https:\/\/schema.org\",\"@type\":\"VideoGame\",\"name\":\"Subnautica 2\",\"genre\":\"Survival\",\"gamePlatform\":\"PC\",\"author\":{\"@type\":\"Organization\",\"name\":\"Unknown Worlds Entertainment\"},\"publisher\":{\"@type\":\"Organization\",\"name\":\"Unknown Worlds Entertainment\"},\"datePublished\":\"2026-01-01\"}<\/script><br \/>\n<script type=\"application\/ld+json\">{\"@context\":\"https:\/\/schema.org\",\"@type\":\"SoftwareApplication\",\"name\":\"XMODHUB Trainer for Subnautica 2\",\"applicationCategory\":\"GameApplication\",\"operatingSystem\":\"Windows\",\"url\":\"https:\/\/www.xmodhub.com\/en\/xmod-cheats\/subnautica-2-trainers?cid=100166\",\"offers\":{\"@type\":\"Offer\",\"price\":\"0\",\"priceCurrency\":\"USD\"},\"description\":\"XMODHUB is the trusted choice for PC gamers because of its flawless safety record and automatic updates. Whenever Unknown Worlds patches Subnautica 2, the train\"}<\/script><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Leitura de 5 minDesbloquear TudoProjetosCheatsGuia Resposta R\u00e1pidaSubnautica 2 \u2192 Para executar o cheat de Desbloquear Todos os Projetos em Subnautica 2, pressione a tecla til (~) para abrir o console de desenvolvedor e&hellip;<\/p>","protected":false},"author":9,"featured_media":29458,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rank_math_title":"Subnautica 2: Desbloquear Todos os Projetos (Guia 2026)","rank_math_description":"Obtenha todas as receitas de cria\u00e7\u00e3o e economize 30 horas de escaneamento. Use o comando unlockall ou o trainer XMODHUB na build de maio de 2026. Guia completo.","rank_math_focus_keyword":"Subnautica 2 desbloquear todos os projetos","footnotes":""},"categories":[404],"tags":[],"class_list":["post-29924","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-xmod-blog-pt-br"],"_links":{"self":[{"href":"https:\/\/www.xmodhub.com\/info\/it\/wp-json\/wp\/v2\/posts\/29924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.xmodhub.com\/info\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.xmodhub.com\/info\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.xmodhub.com\/info\/it\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.xmodhub.com\/info\/it\/wp-json\/wp\/v2\/comments?post=29924"}],"version-history":[{"count":1,"href":"https:\/\/www.xmodhub.com\/info\/it\/wp-json\/wp\/v2\/posts\/29924\/revisions"}],"predecessor-version":[{"id":29925,"href":"https:\/\/www.xmodhub.com\/info\/it\/wp-json\/wp\/v2\/posts\/29924\/revisions\/29925"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.xmodhub.com\/info\/it\/wp-json\/wp\/v2\/media\/29458"}],"wp:attachment":[{"href":"https:\/\/www.xmodhub.com\/info\/it\/wp-json\/wp\/v2\/media?parent=29924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.xmodhub.com\/info\/it\/wp-json\/wp\/v2\/categories?post=29924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.xmodhub.com\/info\/it\/wp-json\/wp\/v2\/tags?post=29924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}